{"id":919,"count":1,"description":"","link":"https:\/\/clubalmacen.com\/chile\/tag\/lo-valledor\/","name":"Lo Valledor","slug":"lo-valledor","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/clubalmacen.com\/chile\/wp-json\/wp\/v2\/tags\/919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clubalmacen.com\/chile\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/clubalmacen.com\/chile\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/clubalmacen.com\/chile\/wp-json\/wp\/v2\/posts?tags=919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}