{"id":61,"count":33,"description":"Noticias Relacionadas con el Fondo de SERCOTEC Almacenes de Chile que en su versi\u00f3n 2019 se presenta  bajo el nombre Digitaliza tu Almac\u00e9n y esta enfocado en la compra de tecnolog\u00eda de punto de venta","link":"https:\/\/clubalmacen.com\/chile\/category\/almacenes-de-chile\/","name":"Almacenes de Chile","slug":"almacenes-de-chile","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/clubalmacen.com\/chile\/wp-json\/wp\/v2\/categories\/61","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clubalmacen.com\/chile\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/clubalmacen.com\/chile\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/clubalmacen.com\/chile\/wp-json\/wp\/v2\/posts?categories=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}